{"id":50,"date":"2023-01-13T20:00:00","date_gmt":"2023-01-13T11:00:00","guid":{"rendered":"http:\/\/noplannogame.com\/?p=50"},"modified":"2024-02-23T23:13:23","modified_gmt":"2024-02-23T14:13:23","slug":"gothique-dark-souls-ruines-eternelles","status":"publish","type":"post","link":"https:\/\/noplannogame.com\/index.php\/2023\/01\/13\/gothique-dark-souls-ruines-eternelles\/","title":{"rendered":"Gothique : Dark Souls, ruines \u00e9ternelles"},"content":{"rendered":"\n<p class=\"has-text-align-center\">La repr\u00e9sentation de l&rsquo;architecture dans Dark Souls tourne autour d&rsquo;un th\u00e8me central : la mort. Dark Souls transmet l&rsquo;id\u00e9e que les morts-vivants ne sont pas des monstres d\u00e9cha\u00een\u00e9s ou des \u00eatres mystiques, mais des maudits, ceux \u00e0 qui on a simplement refus\u00e9 la mort et le repos. Sans le confort d&rsquo;une mort in\u00e9vitable, une seule fin les attend : la fin de toutes choses.<\/p>\n\n\n\n<p class=\"has-text-align-center\">C\u2019est l\u2019une des raisons pour laquelle Dark Souls peut s\u2019av\u00e9rer si marquant : la fa\u00e7on dont le jeu combine cet effacement de la mort avec un sens distinct de l&rsquo;espace. La r\u00e9f\u00e9rence \u00e0 un royaume pass\u00e9, le monde froid traduisant des terres d\u00e9sol\u00e9es et lointaines, ainsi qu\u2019une sensation d\u2019enfermement malgr\u00e9 le monde ouvert, le tout donnant un sens primordial \u00e0 l&rsquo;architecture, et \u00e0 sa fonction de prison, de refuge ou de conteneur pour les morts. L&rsquo;image architecturale centrale de la s\u00e9rie est un \u00e9difice en ruine dans lequel errent les morts, le sens \u00e9tant retir\u00e9 par le temps \u00e0 la fois des corps en d\u00e9composition des morts-vivants et des pierres et st\u00e8les qui les entourent.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Gothique : Dark Souls, ruines \u00e9ternelles | No Plan No Game : Architecture et jeu vid\u00e9o\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/6BCfB98hSSg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La repr\u00e9sentation de l&rsquo;architecture dans Dark Souls tourne autour d&rsquo;un th\u00e8me central : la mort. Dark Souls transmet l&rsquo;id\u00e9e que les morts-vivants ne sont pas des monstres d\u00e9cha\u00een\u00e9s ou des \u00eatres mystiques, mais des maudits, ceux \u00e0 qui on a simplement refus\u00e9 la mort et le repos. Sans le confort d&rsquo;une mort in\u00e9vitable, une seule [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-50","post","type-post","status-publish","format-standard","hentry","category-video"],"_links":{"self":[{"href":"https:\/\/noplannogame.com\/index.php\/wp-json\/wp\/v2\/posts\/50","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noplannogame.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noplannogame.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noplannogame.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/noplannogame.com\/index.php\/wp-json\/wp\/v2\/comments?post=50"}],"version-history":[{"count":1,"href":"https:\/\/noplannogame.com\/index.php\/wp-json\/wp\/v2\/posts\/50\/revisions"}],"predecessor-version":[{"id":51,"href":"https:\/\/noplannogame.com\/index.php\/wp-json\/wp\/v2\/posts\/50\/revisions\/51"}],"wp:attachment":[{"href":"https:\/\/noplannogame.com\/index.php\/wp-json\/wp\/v2\/media?parent=50"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noplannogame.com\/index.php\/wp-json\/wp\/v2\/categories?post=50"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noplannogame.com\/index.php\/wp-json\/wp\/v2\/tags?post=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}